{"id":40,"date":"2014-07-01T14:43:50","date_gmt":"2014-07-01T14:43:50","guid":{"rendered":"https:\/\/bioptic.net\/?page_id=40"},"modified":"2017-04-24T10:11:06","modified_gmt":"2017-04-24T10:11:06","slug":"cirugia","status":"publish","type":"page","link":"https:\/\/www.bioptic.net\/es\/cirugia\/","title":{"rendered":"Cirug\u00eda"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_textblock  avia-builder-el-first   container_wrap sidebar_right'  ><div  class='avia-slideshow av-av_slideshow_full-ca9aa842821e3a17b01b4e99e5d40465 avia-slideshow-no scaling av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 12.5%;'><li  class='avia-slideshow-slide av-av_slideshow_full-ca9aa842821e3a17b01b4e99e5d40465__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-av_slideshow_full-ca9aa842821e3a17b01b4e99e5d40465__0 caption_fullwidth caption_center'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >CIRUG\u00cdA REFRACTIVA<\/h2><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-2142 avia-img-lazy-loading-not-2142\"  src=\"https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2.jpg\" width=\"2000\" height=\"250\" title='slider-cirugia2' alt='Primer plano de un ojo azul con una ret\u00edcula digital brillante superpuesta, que sugiere un escaneado ocular o una identificaci\u00f3n biom\u00e9trica, sobre un fondo azul claro. Solo se ve el lado derecho de la cara de una persona.'  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2.jpg 2000w, https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2-300x37.jpg 300w, https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2-1030x128.jpg 1030w, https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2-1500x187.jpg 1500w, https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2-705x88.jpg 705w, https:\/\/www.bioptic.net\/wp-content\/uploads\/2014\/07\/slider-cirugia2-450x56.jpg 450w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div><\/li><\/ul><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-40'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><b>\u00a1Disfruta de una vida sin lentes de contacto ni gafas!<\/b><\/p>\n<p>Corregir los problemas de la visi\u00f3n como la miop\u00eda o el astigmatismo ya es posible con la cirug\u00eda refractiva, que permite tratar y corregir las alteraciones\u00a0del ojo humano.<\/p>\n<p>Un riguroso\u00a0examen preoperatorio\u00a0en nuestro centro permite\u00a0al equipo oftalmol\u00f3gico dar una m\u00e1xima garant\u00eda de\u00a0los resultados quir\u00fargicos.<\/p>\n<p><b>La recuperaci\u00f3n es pr\u00e1cticamente\u00a0inmediata, con una mejora\u00a0postoperatoria r\u00e1pida e indolora.<\/b><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-40","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bioptic.net\/es\/cirugia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bioptic.net\/es\/cirugia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bioptic\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-24T10:11:06+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/cirugia\\\/\",\"url\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/cirugia\\\/\",\"name\":\"Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/#website\"},\"datePublished\":\"2014-07-01T14:43:50+00:00\",\"dateModified\":\"2017-04-24T10:11:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/cirugia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bioptic.net\\\/es\\\/cirugia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/cirugia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cirug\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/\",\"name\":\"Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona\",\"description\":\"Centro de la visi\u00f3n en Barcelona. Orto-K, Optometr\u00eda, \u00d3ptica, Lentes de Contacto, CRT, Problemas de visi\u00f3n, Terapia Visual.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bioptic.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bioptic.net\/es\/cirugia\/","og_locale":"es_ES","og_type":"article","og_title":"Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona","og_url":"https:\/\/www.bioptic.net\/es\/cirugia\/","og_site_name":"Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona","article_publisher":"https:\/\/www.facebook.com\/bioptic","article_modified_time":"2017-04-24T10:11:06+00:00","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bioptic.net\/es\/cirugia\/","url":"https:\/\/www.bioptic.net\/es\/cirugia\/","name":"Cirug\u00eda - Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona","isPartOf":{"@id":"https:\/\/www.bioptic.net\/es\/#website"},"datePublished":"2014-07-01T14:43:50+00:00","dateModified":"2017-04-24T10:11:06+00:00","breadcrumb":{"@id":"https:\/\/www.bioptic.net\/es\/cirugia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bioptic.net\/es\/cirugia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bioptic.net\/es\/cirugia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bioptic.net\/es\/"},{"@type":"ListItem","position":2,"name":"Cirug\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.bioptic.net\/es\/#website","url":"https:\/\/www.bioptic.net\/es\/","name":"Bi\u00f2ptic - Orto-K, Optometria y \u00d3ptica en Barcelona","description":"Centro de la visi\u00f3n en Barcelona. Orto-K, Optometr\u00eda, \u00d3ptica, Lentes de Contacto, CRT, Problemas de visi\u00f3n, Terapia Visual.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bioptic.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/pages\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":0,"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bioptic.net\/es\/wp-json\/wp\/v2\/media?parent=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}